{"id":28246,"count":1,"description":"","link":"https:\/\/app.60day.cn\/appday\/tag\/%e4%b8%80%e4%bb%bd%e8%bd%af%e8%91%97%e5%8f%af%e7%94%a8%e4%ba%8e%e4%b8%a4%e4%b8%aaapp%e5%90%97\/","name":"\u4e00\u4efd\u8f6f\u8457\u53ef\u7528\u4e8e\u4e24\u4e2aapp\u5417","slug":"%e4%b8%80%e4%bb%bd%e8%bd%af%e8%91%97%e5%8f%af%e7%94%a8%e4%ba%8e%e4%b8%a4%e4%b8%aaapp%e5%90%97","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/app.60day.cn\/appday\/wp-json\/wp\/v2\/tags\/28246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/app.60day.cn\/appday\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/app.60day.cn\/appday\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/app.60day.cn\/appday\/wp-json\/wp\/v2\/posts?tags=28246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}