{"id":33798,"count":3,"description":"","link":"https:\/\/app.60day.cn\/appday\/tag\/ipa%e4%b8%8a%e4%bc%a0%e5%85%8d%e8%b4%b9%e5%b7%a5%e5%85%b7\/","name":"ipa\u4e0a\u4f20\u514d\u8d39\u5de5\u5177","slug":"ipa%e4%b8%8a%e4%bc%a0%e5%85%8d%e8%b4%b9%e5%b7%a5%e5%85%b7","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/app.60day.cn\/appday\/wp-json\/wp\/v2\/tags\/33798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/app.60day.cn\/appday\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/app.60day.cn\/appday\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/app.60day.cn\/appday\/wp-json\/wp\/v2\/posts?tags=33798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}